{"id":12708,"date":"2020-05-12T17:04:26","date_gmt":"2020-05-12T10:34:26","guid":{"rendered":"http:\/\/www.uabdev.com.mm\/?page_id=12708"},"modified":"2022-07-30T09:38:42","modified_gmt":"2022-07-30T03:08:42","slug":"annual-report-2018","status":"publish","type":"page","link":"http:\/\/www.uab.com.mm\/mm\/investors\/annual-report-2018\/","title":{"rendered":"Annual Report 2018"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"12708\" class=\"elementor elementor-12708\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-df67cdf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"df67cdf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-21565a7\" data-id=\"21565a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40c037a elementor-widget elementor-widget-text-editor\" data-id=\"40c037a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 14px; font-family: inherit;\"><span style=\"color: #111;\">Investors<\/span> \/ <a href=\"\/investors\/our-reports\/\">Our Reports<\/a> \/ <span style=\"color: #39b54a;\">Annual Reports 2018<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e2084b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e2084b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ccd1614\" data-id=\"ccd1614\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4aeec2 elementor-widget elementor-widget-image\" data-id=\"b4aeec2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"544\" src=\"\/wp-content\/uploads\/2022\/03\/Annual-Report_2018-1024x544.jpg\" class=\"attachment-large size-large wp-image-42260\" alt=\"Annual Report 2018 1024x544\" srcset=\"\/wp-content\/uploads\/2022\/03\/Annual-Report_2018-1024x544.jpg 1024w, \/wp-content\/uploads\/2022\/03\/Annual-Report_2018-300x159.jpg 300w, \/wp-content\/uploads\/2022\/03\/Annual-Report_2018-768x408.jpg 768w, \/wp-content\/uploads\/2022\/03\/Annual-Report_2018-1536x817.jpg 1536w, \/wp-content\/uploads\/2022\/03\/Annual-Report_2018-2048x1089.jpg 2048w, \/wp-content\/uploads\/2022\/03\/Annual-Report_2018-16x9.jpg 16w, \/wp-content\/uploads\/2022\/03\/Annual-Report_2018-600x319.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4ca0bc6\" data-id=\"4ca0bc6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c03cca elementor-widget elementor-widget-spacer\" data-id=\"3c03cca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1af3a1 elementor-widget elementor-widget-heading\" data-id=\"f1af3a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Annual Report 2018<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd4c48c elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"fd4c48c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"\/pdfs\/annual_report\/Annual_Report2018.pdf\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Annual Report 2018 (English) Version\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-file-pdf\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"\/pdfs\/annual_report\/Annual_Report2018.pdf\" >\n\t\t\t\t\t\t\tAnnual Report 2018 (English) Version\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ca003c elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7ca003c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"\/pdfs\/annual_report\/annual_report2018_(Myanmar)_version.pdf\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Annual Report 2018 (Myanmar) Version\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-file-pdf\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"\/pdfs\/annual_report\/annual_report2018_(Myanmar)_version.pdf\" >\n\t\t\t\t\t\t\tAnnual Report 2018 (Myanmar) Version\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac5f2b8 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ac5f2b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a0b487a\" data-id=\"a0b487a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f3cca2 elementor-widget elementor-widget-image\" data-id=\"1f3cca2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"631\" height=\"376\" src=\"\/wp-content\/uploads\/2020\/04\/annual-report_0-2.jpg\" class=\"attachment-large size-large wp-image-10766\" alt=\"Annual report 0 2\" srcset=\"\/wp-content\/uploads\/2020\/04\/annual-report_0-2.jpg 631w, \/wp-content\/uploads\/2020\/04\/annual-report_0-2-300x179.jpg 300w, \/wp-content\/uploads\/2020\/04\/annual-report_0-2-600x358.jpg 600w\" sizes=\"auto, (max-width: 631px) 100vw, 631px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-eb9f6a4\" data-id=\"eb9f6a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e443ceb elementor-widget elementor-widget-heading\" data-id=\"e443ceb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Annual Report 2018<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38cadaa elementor-widget elementor-widget-text-editor\" data-id=\"38cadaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a class=\"susdownbtn\" href=\"\/pdfs\/annual report\/Annual Report 2018.pdf\" target=\"_blank\" rel=\"noopener\"><i class=\"fa fa-download\"><\/i> Annual Report 2018 (English) Version<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b93ee4d elementor-widget elementor-widget-text-editor\" data-id=\"b93ee4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a class=\"susdownbtn\" href=\"\/pdfs\/annual%20report\/annual%20report%202018%20(Myanmar)%20version.pdf\" target=\"_blank\" rel=\"noopener\"><i class=\"fa fa-download\"><\/i> Annual Report 2018 (Myanmar) Version<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13ab780 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"13ab780\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"\/pdfs\/annual%20report\/Annual%20Report%202018.pdf\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Annual Report 2018 (English) Version\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-file-pdf\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"\/pdfs\/annual%20report\/Annual%20Report%202018.pdf\" >\n\t\t\t\t\t\t\tAnnual Report 2018 (English) Version\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47761a7 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"47761a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"\/pdfs\/annual%20report\/annual%20report%202018%20(Myanmar)%20version.pdf\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Annual Report 2018 (Myanmar) Version\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-file-pdf\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"\/pdfs\/annual%20report\/annual%20report%202018%20(Myanmar)%20version.pdf\" >\n\t\t\t\t\t\t\tAnnual Report 2018 (Myanmar) Version\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7dfd2ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7dfd2ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9c9e6ba\" data-id=\"9c9e6ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2e83db elementor-widget elementor-widget-spacer\" data-id=\"b2e83db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Investors \/ Our Reports \/ Annual Reports 2018 Annual Report 2018 &#8230; <\/p>","protected":false},"author":2,"featured_media":0,"parent":25752,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-12708","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Annual Report 2018 - uab bank<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uab.com.mm\/mm\/investors\/annual-report-2018\/\" \/>\n<meta property=\"og:locale\" content=\"my_MM\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Annual Report 2018 - uab bank\" \/>\n<meta property=\"og:description\" content=\"Investors \/ Our Reports \/ Annual Reports 2018 Annual Report 2018 ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uab.com.mm\/mm\/investors\/annual-report-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"uab bank\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uabbankmm\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-30T03:08:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uab.com.mm\/wp-content\/uploads\/2022\/03\/Annual-Report_2018-1024x544.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uab.com.mm\\\/investors\\\/annual-report-2018\\\/\",\"url\":\"https:\\\/\\\/www.uab.com.mm\\\/investors\\\/annual-report-2018\\\/\",\"name\":\"Annual Report 2018 - uab bank\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uab.com.mm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uab.com.mm\\\/investors\\\/annual-report-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uab.com.mm\\\/investors\\\/annual-report-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uab.com.mm\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Annual-Report_2018-1024x544.jpg\",\"datePublished\":\"2020-05-12T10:34:26+00:00\",\"dateModified\":\"2022-07-30T03:08:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uab.com.mm\\\/investors\\\/annual-report-2018\\\/#breadcrumb\"},\"inLanguage\":\"my-MM\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uab.com.mm\\\/investors\\\/annual-report-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"my-MM\",\"@id\":\"https:\\\/\\\/www.uab.com.mm\\\/investors\\\/annual-report-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.uab.com.mm\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Annual-Report_2018-1024x544.jpg\",\"contentUrl\":\"https:\\\/\\\/www.uab.com.mm\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Annual-Report_2018-1024x544.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uab.com.mm\\\/investors\\\/annual-report-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Investors\",\"item\":\"https:\\\/\\\/www.uab.com.mm\\\/investors\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Annual Report 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uab.com.mm\\\/#website\",\"url\":\"https:\\\/\\\/www.uab.com.mm\\\/\",\"name\":\"uab bank\",\"description\":\"Connect. Create. Change.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uab.com.mm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"my-MM\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Annual Report 2018 - uab bank","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uab.com.mm\/mm\/investors\/annual-report-2018\/","og_locale":"my_MM","og_type":"article","og_title":"Annual Report 2018 - uab bank","og_description":"Investors \/ Our Reports \/ Annual Reports 2018 Annual Report 2018 ...","og_url":"https:\/\/www.uab.com.mm\/mm\/investors\/annual-report-2018\/","og_site_name":"uab bank","article_publisher":"https:\/\/www.facebook.com\/uabbankmm","article_modified_time":"2022-07-30T03:08:42+00:00","og_image":[{"url":"https:\/\/www.uab.com.mm\/wp-content\/uploads\/2022\/03\/Annual-Report_2018-1024x544.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uab.com.mm\/investors\/annual-report-2018\/","url":"https:\/\/www.uab.com.mm\/investors\/annual-report-2018\/","name":"Annual Report 2018 - uab bank","isPartOf":{"@id":"https:\/\/www.uab.com.mm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uab.com.mm\/investors\/annual-report-2018\/#primaryimage"},"image":{"@id":"https:\/\/www.uab.com.mm\/investors\/annual-report-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uab.com.mm\/wp-content\/uploads\/2022\/03\/Annual-Report_2018-1024x544.jpg","datePublished":"2020-05-12T10:34:26+00:00","dateModified":"2022-07-30T03:08:42+00:00","breadcrumb":{"@id":"https:\/\/www.uab.com.mm\/investors\/annual-report-2018\/#breadcrumb"},"inLanguage":"my-MM","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uab.com.mm\/investors\/annual-report-2018\/"]}]},{"@type":"ImageObject","inLanguage":"my-MM","@id":"https:\/\/www.uab.com.mm\/investors\/annual-report-2018\/#primaryimage","url":"https:\/\/www.uab.com.mm\/wp-content\/uploads\/2022\/03\/Annual-Report_2018-1024x544.jpg","contentUrl":"https:\/\/www.uab.com.mm\/wp-content\/uploads\/2022\/03\/Annual-Report_2018-1024x544.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uab.com.mm\/investors\/annual-report-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Investors","item":"https:\/\/www.uab.com.mm\/investors\/"},{"@type":"ListItem","position":2,"name":"Annual Report 2018"}]},{"@type":"WebSite","@id":"https:\/\/www.uab.com.mm\/#website","url":"https:\/\/www.uab.com.mm\/","name":"uab \u1018\u100f\u103a\u1021\u1014\u1031\u1016\u103c\u1004\u1037\u103a","description":"Connect. Create. Change.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uab.com.mm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"my-MM"}]}},"_links":{"self":[{"href":"http:\/\/www.uab.com.mm\/mm\/wp-json\/wp\/v2\/pages\/12708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.uab.com.mm\/mm\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.uab.com.mm\/mm\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.uab.com.mm\/mm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.uab.com.mm\/mm\/wp-json\/wp\/v2\/comments?post=12708"}],"version-history":[{"count":0,"href":"http:\/\/www.uab.com.mm\/mm\/wp-json\/wp\/v2\/pages\/12708\/revisions"}],"up":[{"embeddable":true,"href":"http:\/\/www.uab.com.mm\/mm\/wp-json\/wp\/v2\/pages\/25752"}],"wp:attachment":[{"href":"http:\/\/www.uab.com.mm\/mm\/wp-json\/wp\/v2\/media?parent=12708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}